{"id":7,"count":1,"description":"","link":"https:\/\/www.aizu-xaverio.ed.jp\/h-school\/category\/news-junior-high\/","name":"\u4e2d\u9ad8\u5171\u901a\u306e\u304a\u77e5\u3089\u305b","slug":"news-junior-high","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.aizu-xaverio.ed.jp\/h-school\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aizu-xaverio.ed.jp\/h-school\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.aizu-xaverio.ed.jp\/h-school\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.aizu-xaverio.ed.jp\/h-school\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}